{"id":8,"count":54,"description":"Marine Litter","link":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/","name":"Marine Litter","slug":"marine-litter","taxonomy":"category","parent":1935,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marine Litter Archives - Marine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marine Litter Archives - Marine\" \/>\n<meta property=\"og:description\" content=\"Marine Litter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/\" \/>\n<meta property=\"og:site_name\" content=\"Marine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script nonce='6a98711935d86' type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/category\\\/marine-environment\\\/marine-litter\\\/\",\"url\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/category\\\/marine-environment\\\/marine-litter\\\/\",\"name\":\"Marine Litter Archives - Marine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/category\\\/marine-environment\\\/marine-litter\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/category\\\/marine-environment\\\/marine-litter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marine Environment\",\"item\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/category\\\/marine-environment\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marine Litter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/#website\",\"url\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/\",\"name\":\"Marine\",\"description\":\"Scottish Government Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.gov.scot\\\/marine-scotland\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marine Litter Archives - Marine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/","og_locale":"en_GB","og_type":"article","og_title":"Marine Litter Archives - Marine","og_description":"Marine Litter","og_url":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/","og_site_name":"Marine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/","url":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/","name":"Marine Litter Archives - Marine","isPartOf":{"@id":"https:\/\/blogs.gov.scot\/marine-scotland\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/marine-litter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.gov.scot\/marine-scotland\/"},{"@type":"ListItem","position":2,"name":"Marine Environment","item":"https:\/\/blogs.gov.scot\/marine-scotland\/category\/marine-environment\/"},{"@type":"ListItem","position":3,"name":"Marine Litter"}]},{"@type":"WebSite","@id":"https:\/\/blogs.gov.scot\/marine-scotland\/#website","url":"https:\/\/blogs.gov.scot\/marine-scotland\/","name":"Marine","description":"Scottish Government Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.gov.scot\/marine-scotland\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/categories\/1935"}],"wp:post_type":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}