{"id":890,"count":1,"description":"","link":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/","name":"global assessments","slug":"global-assessments","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>global assessments Archives - Marine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"global assessments Archives - Marine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/\" \/>\n<meta property=\"og:site_name\" content=\"Marine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/\",\"url\":\"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/\",\"name\":\"global assessments Archives - Marine\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.gov.scot\/marine-scotland\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogs.gov.scot\/marine-scotland\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"global assessments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.gov.scot\/marine-scotland\/#website\",\"url\":\"https:\/\/blogs.gov.scot\/marine-scotland\/\",\"name\":\"Marine\",\"description\":\"Scottish Government Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.gov.scot\/marine-scotland\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"global assessments Archives - Marine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/","og_locale":"en_GB","og_type":"article","og_title":"global assessments Archives - Marine","og_url":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/","og_site_name":"Marine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/","url":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/","name":"global assessments Archives - Marine","isPartOf":{"@id":"https:\/\/blogs.gov.scot\/marine-scotland\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.gov.scot\/marine-scotland\/tag\/global-assessments\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.gov.scot\/marine-scotland\/"},{"@type":"ListItem","position":2,"name":"global assessments"}]},{"@type":"WebSite","@id":"https:\/\/blogs.gov.scot\/marine-scotland\/#website","url":"https:\/\/blogs.gov.scot\/marine-scotland\/","name":"Marine","description":"Scottish Government Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.gov.scot\/marine-scotland\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/tags\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.gov.scot\/marine-scotland\/wp-json\/wp\/v2\/posts?tags=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}