{"id":50,"count":5,"description":"","link":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/","name":"independence","slug":"independence","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>independence Archives - Scotland&#039;s Economy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"independence Archives - Scotland&#039;s Economy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/\" \/>\n<meta property=\"og:site_name\" content=\"Scotland&#039;s Economy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script nonce='6a97a5aa49882' type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/tag\\\/independence\\\/\",\"url\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/tag\\\/independence\\\/\",\"name\":\"independence Archives - Scotland&#039;s Economy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/tag\\\/independence\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/tag\\\/independence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"independence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/#website\",\"url\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/\",\"name\":\"Scotland&#039;s Economy\",\"description\":\"Scottish Government Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.gov.scot\\\/scotlands-economy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"independence Archives - Scotland&#039;s Economy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/","og_locale":"en_GB","og_type":"article","og_title":"independence Archives - Scotland&#039;s Economy","og_url":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/","og_site_name":"Scotland&#039;s Economy","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/","url":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/","name":"independence Archives - Scotland&#039;s Economy","isPartOf":{"@id":"https:\/\/blogs.gov.scot\/scotlands-economy\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.gov.scot\/scotlands-economy\/tag\/independence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.gov.scot\/scotlands-economy\/"},{"@type":"ListItem","position":2,"name":"independence"}]},{"@type":"WebSite","@id":"https:\/\/blogs.gov.scot\/scotlands-economy\/#website","url":"https:\/\/blogs.gov.scot\/scotlands-economy\/","name":"Scotland&#039;s Economy","description":"Scottish Government Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.gov.scot\/scotlands-economy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blogs.gov.scot\/scotlands-economy\/wp-json\/wp\/v2\/tags\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gov.scot\/scotlands-economy\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.gov.scot\/scotlands-economy\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.gov.scot\/scotlands-economy\/wp-json\/wp\/v2\/posts?tags=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}